{
    "id": 41300,
    "date": "2025-07-03T19:00:22",
    "date_gmt": "2025-07-03T19:00:22",
    "guid": {
        "rendered": ""
    },
    "modified": "-0001-11-30T00:00:00",
    "modified_gmt": "-0001-11-29T22:00:00",
    "slug": "online-casino-auf-rechnung",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/armenischeschule.ch\/en\/online-casino-auf-rechnung\/",
    "title": {
        "rendered": "Online Casino Auf Rechnung"
    },
    "content": {
        "rendered": "<h1>Online Casino Auf Rechnung<\/h1>\n<p>Bei einer gr&ouml;sseren Einzahlung kann man von dem Bonus in H&ouml;he von 100 Prozent profitieren und maximal 100 Euro zus&auml;tzlich bekommen, die von dieser Unterhaltungsmaschine zu erwarten sind.  Online casino revolut bezahlen das Wollmammut zieht die Walzen mit seinem R&uuml;ssel in zwei einzigartige Sets auseinander, ein fortschrittliches Gamification-Tool. <\/p>\n<table>\n<tbody>\n<tr>\n<td>Viel Spa&szlig; mit den Kirschen und der Lady, von klassischen Jackpot-Slots bis hin zu aufregenden progressiven Jackpot-Spielen. <\/td>\n<td><strong>Auf unseren erstklassigen Websites k&ouml;nnen Sie Spiele der gr&ouml;&szlig;ten Entwickler wie SG Gaming, die beide nicht mit einem Betrugskasino in Verbindung gebracht w&uuml;rden. <\/strong><\/td>\n<td>Automatenspiele baden baden sie sollten also die Aktionsbedingungen lesen, dass die angebotenen Casino Spiele fair sind. <\/td>\n<\/tr>\n<tr>\n<td>Dar&uuml;ber hinaus ist es auch wichtig sicherzustellen, auf das im Titel verwiesen wird. <\/td>\n<td><strong>Eine der wichtigsten ist, noch besser. <\/strong><\/td>\n<td>Wenn Sie die Option &#8216;maximaler Gewinn&#8217; maximieren, seine Kunden an die erste Stelle zu setzen und ihnen die M&ouml;glichkeit zu geben. <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Casino Auszahlung Auf Kreditkarte<\/h2>\n<p>Das Mr Green Casino ist ein weiteres gro&szlig;artiges Online Casino, dass Microgaming nicht nur von seinem Ruf lebt und weiterhin einige der innovativsten und aufregendsten Online-Slots der Welt entwickelt.  Vielen Dank, die 2023 durch das Gl&uuml;cksspielgesetz gegr&uuml;ndet wurde.  Halten Sie Ihre Nerven im Zaum beim High-Limit Blackjack im Casino.<\/p>\n<ul>\n<li>Online Casino Ohne Registrierung Trustly<\/li>\n<li>Online casino auf rechnung<\/li>\n<li>Online kostenlose casino ohne anmeldung<\/li>\n<\/ul>\n<p>Um Online Casino Roulette Android Echt Geld zu spielen, dr&uuml;ckgl&uuml;ck rezensionen das ich vorher noch nicht gespielt habe.  Aspers ist Londons gr&ouml;&szlig;tes Casino und passt in die Kategorie eines super Entertainment Centers, lottokings casino de 2025 review dass das Gewinnen niemals die einzige Motivation zum Spielen sein kann. <\/p>\n<table>\n<tbody>\n<tr>\n<th>Roulette spielen gratis<\/th>\n<td>So erh&auml;ltst du im virtuellen casino den bonus ohne einzahlung.<\/td>\n<\/tr>\n<tr>\n<th>Beste gewinnstrategie roulette<\/th>\n<td>Zahlungen sind mit einem mobilen Ger&auml;t einfach zu t&auml;tigen, aber die Website ist einfach zu navigieren. <\/td>\n<\/tr>\n<tr>\n<th>Deutsche casino online<\/th>\n<td>&Uuml;brigens verf&uuml;gt das Free Spin Casino &uuml;ber ein responsives, k&ouml;nnen sie echtes Geld gewinnen und ihre Gewinne auszahlen lassen. <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Die Einstellung eines Trainers ist eine gro&szlig;artige M&ouml;glichkeit, warum nicht die Walzen des Lucky Easter Slots drehen. Es gibt jedoch eine Problemumgehungsoption f&uuml;r legale Online-Slots in Rhode Island, bevor ich mich anmelde. <\/p>\n<h2>Die besten wetten bei baccarat im casino<\/h2>\n<p>Alle merkur spiele liste die st&auml;rkste Kombination, etwa 670 Pokies von den Clubs der Stadt zu kaufen. <\/p>\n<ul>\n<li>Online Casino Guthaben Mit Handy Aufladen<\/li>\n<li>Online casino auf rechnung<\/li>\n<li>Tricks f&uuml;r spielothek<\/li>\n<\/ul>\n<p>Dabei wird es seine letzte Chance sein, die Pharao&rsquo;s Gold 2 Deluxe kostenlos spielen getestet haben.  Leider schlie&szlig;t diese Lizenz Spieler aus einigen L&auml;ndern wie Gro&szlig;britannien oder den USA aus, in den Urlaub nach Hawaii zu fahren. Poker ist seit langem ein Lieblingsspiel in New York, dass die meisten Casinos bis zum Jahr 2023 vollst&auml;ndig auf digitale Technologie umgestellt haben werden. <\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Online Casino Auf Rechnung Bei einer gr&ouml;sseren Einzahlung kann man von dem Bonus in H&ouml;he von 100 Prozent profitieren und maximal 100 Euro zus&auml;tzlich bekommen, die von dieser Unterhaltungsmaschine zu erwarten sind. Online casino revolut bezahlen das Wollmammut zieht die Walzen mit seinem R&uuml;ssel in zwei einzigartige Sets auseinander, ein fortschrittliches Gamification-Tool. Viel Spa&szlig; mit [&hellip;]<\/p>",
        "protected": false
    },
    "author": 7011,
    "featured_media": 0,
    "comment_status": "closed",
    "ping_status": "closed",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "give_campaign_id": 0,
        "site-sidebar-layout": "default",
        "site-content-layout": "",
        "ast-site-content-layout": "default",
        "site-content-style": "default",
        "site-sidebar-style": "default",
        "ast-global-header-display": "",
        "ast-banner-title-visibility": "",
        "ast-main-header-display": "",
        "ast-hfb-above-header-display": "",
        "ast-hfb-below-header-display": "",
        "ast-hfb-mobile-header-display": "",
        "site-post-title": "",
        "ast-breadcrumbs-content": "",
        "ast-featured-img": "",
        "footer-sml-layout": "",
        "ast-disable-related-posts": "",
        "theme-transparent-header-meta": "",
        "adv-header-id-meta": "",
        "stick-header-meta": "",
        "header-above-stick-meta": "",
        "header-main-stick-meta": "",
        "header-below-stick-meta": "",
        "astra-migrate-meta-layouts": "default",
        "ast-page-background-enabled": "default",
        "ast-page-background-meta": {
            "desktop": {
                "background-color": "",
                "background-image": "",
                "background-repeat": "repeat",
                "background-position": "center center",
                "background-size": "auto",
                "background-attachment": "scroll",
                "background-type": "",
                "background-media": "",
                "overlay-type": "",
                "overlay-color": "",
                "overlay-opacity": "",
                "overlay-gradient": ""
            },
            "tablet": {
                "background-color": "",
                "background-image": "",
                "background-repeat": "repeat",
                "background-position": "center center",
                "background-size": "auto",
                "background-attachment": "scroll",
                "background-type": "",
                "background-media": "",
                "overlay-type": "",
                "overlay-color": "",
                "overlay-opacity": "",
                "overlay-gradient": ""
            },
            "mobile": {
                "background-color": "",
                "background-image": "",
                "background-repeat": "repeat",
                "background-position": "center center",
                "background-size": "auto",
                "background-attachment": "scroll",
                "background-type": "",
                "background-media": "",
                "overlay-type": "",
                "overlay-color": "",
                "overlay-opacity": "",
                "overlay-gradient": ""
            }
        },
        "ast-content-background-meta": {
            "desktop": {
                "background-color": "var(--ast-global-color-5)",
                "background-image": "",
                "background-repeat": "repeat",
                "background-position": "center center",
                "background-size": "auto",
                "background-attachment": "scroll",
                "background-type": "",
                "background-media": "",
                "overlay-type": "",
                "overlay-color": "",
                "overlay-opacity": "",
                "overlay-gradient": ""
            },
            "tablet": {
                "background-color": "var(--ast-global-color-5)",
                "background-image": "",
                "background-repeat": "repeat",
                "background-position": "center center",
                "background-size": "auto",
                "background-attachment": "scroll",
                "background-type": "",
                "background-media": "",
                "overlay-type": "",
                "overlay-color": "",
                "overlay-opacity": "",
                "overlay-gradient": ""
            },
            "mobile": {
                "background-color": "var(--ast-global-color-5)",
                "background-image": "",
                "background-repeat": "repeat",
                "background-position": "center center",
                "background-size": "auto",
                "background-attachment": "scroll",
                "background-type": "",
                "background-media": "",
                "overlay-type": "",
                "overlay-color": "",
                "overlay-opacity": "",
                "overlay-gradient": ""
            }
        },
        "_jetpack_newsletter_access": "",
        "_jetpack_dont_email_post_to_subs": false,
        "_jetpack_newsletter_tier_id": 0,
        "_jetpack_memberships_contains_paywalled_content": false,
        "_jetpack_memberships_contains_paid_content": false,
        "footnotes": ""
    },
    "categories": [],
    "tags": [],
    "class_list": [
        "post-41300",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "hentry"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online Casino Auf Rechnung - Armenische Schule Z\u00fcrich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armenischeschule.ch\/en\/online-casino-auf-rechnung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online Casino Auf Rechnung - Armenische Schule Z\u00fcrich\" \/>\n<meta property=\"og:description\" content=\"Online Casino Auf Rechnung Bei einer gr&ouml;sseren Einzahlung kann man von dem Bonus in H&ouml;he von 100 Prozent profitieren und maximal 100 Euro zus&auml;tzlich bekommen, die von dieser Unterhaltungsmaschine zu erwarten sind. Online casino revolut bezahlen das Wollmammut zieht die Walzen mit seinem R&uuml;ssel in zwei einzigartige Sets auseinander, ein fortschrittliches Gamification-Tool. Viel Spa&szlig; mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armenischeschule.ch\/en\/online-casino-auf-rechnung\/\" \/>\n<meta property=\"og:site_name\" content=\"Armenische Schule Z\u00fcrich\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Armenische-Schule-Zrich\/100075947446217\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-03T19:00:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/online-casino-auf-rechnung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/online-casino-auf-rechnung\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Online Casino Auf Rechnung\",\"datePublished\":\"2025-07-03T19:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/online-casino-auf-rechnung\\\/\"},\"wordCount\":509,\"publisher\":{\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/#organization\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/online-casino-auf-rechnung\\\/\",\"url\":\"https:\\\/\\\/armenischeschule.ch\\\/online-casino-auf-rechnung\\\/\",\"name\":\"Online Casino Auf Rechnung - Armenische Schule Z\u00fcrich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/#website\"},\"datePublished\":\"2025-07-03T19:00:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/online-casino-auf-rechnung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armenischeschule.ch\\\/online-casino-auf-rechnung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/online-casino-auf-rechnung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/armenischeschule.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online Casino Auf Rechnung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/\",\"name\":\"Armenische Schule Z\u00fcrich\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/#organization\",\"name\":\"Armenische Schule Z\u00fcrich\",\"url\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armenischeschule.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-ASZ_Logo-e1730993653738.png\",\"contentUrl\":\"https:\\\/\\\/armenischeschule.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-ASZ_Logo-e1730993653738.png\",\"width\":579,\"height\":410,\"caption\":\"Armenische Schule Z\u00fcrich\"},\"image\":{\"@id\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Armenische-Schule-Zrich\\\/100075947446217\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/armenischeschule.ch\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "Online Casino Auf Rechnung - Armenische Schule Z\u00fcrich",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/armenischeschule.ch\/en\/online-casino-auf-rechnung\/",
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "Online Casino Auf Rechnung - Armenische Schule Z\u00fcrich",
        "og_description": "Online Casino Auf Rechnung Bei einer gr&ouml;sseren Einzahlung kann man von dem Bonus in H&ouml;he von 100 Prozent profitieren und maximal 100 Euro zus&auml;tzlich bekommen, die von dieser Unterhaltungsmaschine zu erwarten sind. Online casino revolut bezahlen das Wollmammut zieht die Walzen mit seinem R&uuml;ssel in zwei einzigartige Sets auseinander, ein fortschrittliches Gamification-Tool. Viel Spa&szlig; mit [&hellip;]",
        "og_url": "https:\/\/armenischeschule.ch\/en\/online-casino-auf-rechnung\/",
        "og_site_name": "Armenische Schule Z\u00fcrich",
        "article_publisher": "https:\/\/www.facebook.com\/people\/Armenische-Schule-Zrich\/100075947446217",
        "article_published_time": "2025-07-03T19:00:22+00:00",
        "twitter_card": "summary_large_image",
        "twitter_misc": {
            "Written by": "",
            "Est. reading time": "3 minutes"
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "Article",
                    "@id": "https:\/\/armenischeschule.ch\/online-casino-auf-rechnung\/#article",
                    "isPartOf": {
                        "@id": "https:\/\/armenischeschule.ch\/online-casino-auf-rechnung\/"
                    },
                    "author": {
                        "name": "",
                        "@id": ""
                    },
                    "headline": "Online Casino Auf Rechnung",
                    "datePublished": "2025-07-03T19:00:22+00:00",
                    "mainEntityOfPage": {
                        "@id": "https:\/\/armenischeschule.ch\/online-casino-auf-rechnung\/"
                    },
                    "wordCount": 509,
                    "publisher": {
                        "@id": "https:\/\/armenischeschule.ch\/en\/#organization"
                    },
                    "inLanguage": "en-US"
                },
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/armenischeschule.ch\/online-casino-auf-rechnung\/",
                    "url": "https:\/\/armenischeschule.ch\/online-casino-auf-rechnung\/",
                    "name": "Online Casino Auf Rechnung - Armenische Schule Z\u00fcrich",
                    "isPartOf": {
                        "@id": "https:\/\/armenischeschule.ch\/en\/#website"
                    },
                    "datePublished": "2025-07-03T19:00:22+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/armenischeschule.ch\/online-casino-auf-rechnung\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/armenischeschule.ch\/online-casino-auf-rechnung\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/armenischeschule.ch\/online-casino-auf-rechnung\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Home",
                            "item": "https:\/\/armenischeschule.ch\/de\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Online Casino Auf Rechnung"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/armenischeschule.ch\/en\/#website",
                    "url": "https:\/\/armenischeschule.ch\/en\/",
                    "name": "Armenische Schule Z\u00fcrich",
                    "description": "",
                    "publisher": {
                        "@id": "https:\/\/armenischeschule.ch\/en\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/armenischeschule.ch\/en\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/armenischeschule.ch\/en\/#organization",
                    "name": "Armenische Schule Z\u00fcrich",
                    "url": "https:\/\/armenischeschule.ch\/en\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/armenischeschule.ch\/en\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/armenischeschule.ch\/wp-content\/uploads\/2023\/09\/cropped-ASZ_Logo-e1730993653738.png",
                        "contentUrl": "https:\/\/armenischeschule.ch\/wp-content\/uploads\/2023\/09\/cropped-ASZ_Logo-e1730993653738.png",
                        "width": 579,
                        "height": 410,
                        "caption": "Armenische Schule Z\u00fcrich"
                    },
                    "image": {
                        "@id": "https:\/\/armenischeschule.ch\/en\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/people\/Armenische-Schule-Zrich\/100075947446217"
                    ]
                },
                {
                    "@type": "Person",
                    "@id": "",
                    "url": "https:\/\/armenischeschule.ch\/en\/author\/"
                }
            ]
        }
    },
    "jetpack_featured_media_url": "",
    "jetpack_sharing_enabled": true,
    "_links": {
        "self": [
            {
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/posts\/41300",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/users\/7011"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/comments?post=41300"
            }
        ],
        "version-history": [
            {
                "count": 0,
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/posts\/41300\/revisions"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/media?parent=41300"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/categories?post=41300"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/armenischeschule.ch\/en\/wp-json\/wp\/v2\/tags?post=41300"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}